{"id":1691,"date":"2025-06-05T12:46:04","date_gmt":"2025-06-05T10:46:04","guid":{"rendered":"https:\/\/dkllaw.com\/?post_type=person&#038;p=1691"},"modified":"2026-09-01T10:04:29","modified_gmt":"2026-09-01T08:04:29","slug":"christian-valeur-kirkegaard","status":"publish","type":"person","link":"https:\/\/dkllaw.com\/en\/personer\/christian-valeur-kirkegaard\/","title":{"rendered":"CHRISTIAN VALEUR KIRKEGAARD"},"content":{"rendered":"","protected":false},"featured_media":3092,"parent":0,"template":"","meta":{"_acf_changed":false},"person-speciale":[],"stilling":[92],"class_list":["post-1691","person","type-person","status-publish","has-post-thumbnail","hentry","stilling-stipendiat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHRISTIAN VALEUR KIRKEGAARD - Dianati &amp; Klink Larsen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dkllaw.com\/en\/personer\/christian-valeur-kirkegaard\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHRISTIAN VALEUR KIRKEGAARD - Dianati &amp; Klink Larsen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dkllaw.com\/en\/personer\/christian-valeur-kirkegaard\/\" \/>\n<meta property=\"og:site_name\" content=\"Dianati &amp; Klink Larsen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T08:04:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dkllaw.com\/wp-content\/uploads\/Christan-Valeur-Kirkegaard-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1638\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dkllaw.com\\\/personer\\\/christian-valeur-kirkegaard\\\/\",\"url\":\"https:\\\/\\\/dkllaw.com\\\/personer\\\/christian-valeur-kirkegaard\\\/\",\"name\":\"CHRISTIAN VALEUR KIRKEGAARD - Dianati &amp; Klink Larsen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dkllaw.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dkllaw.com\\\/personer\\\/christian-valeur-kirkegaard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dkllaw.com\\\/personer\\\/christian-valeur-kirkegaard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dkllaw.com\\\/wp-content\\\/uploads\\\/Christan-Valeur-Kirkegaard-scaled.jpg\",\"datePublished\":\"2025-06-05T10:46:04+00:00\",\"dateModified\":\"2026-09-01T08:04:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dkllaw.com\\\/personer\\\/christian-valeur-kirkegaard\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dkllaw.com\\\/personer\\\/christian-valeur-kirkegaard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dkllaw.com\\\/personer\\\/christian-valeur-kirkegaard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dkllaw.com\\\/wp-content\\\/uploads\\\/Christan-Valeur-Kirkegaard-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/dkllaw.com\\\/wp-content\\\/uploads\\\/Christan-Valeur-Kirkegaard-scaled.jpg\",\"width\":1638,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dkllaw.com\\\/personer\\\/christian-valeur-kirkegaard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Forside\",\"item\":\"https:\\\/\\\/dkllaw.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personer\",\"item\":\"https:\\\/\\\/dkllaw.com\\\/personer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CHRISTIAN VALEUR KIRKEGAARD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dkllaw.com\\\/#website\",\"url\":\"https:\\\/\\\/dkllaw.com\\\/\",\"name\":\"Dianati &amp; Klink Larsen\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dkllaw.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dkllaw.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dkllaw.com\\\/#organization\",\"name\":\"Dianati &amp; Klink Larsen\",\"url\":\"https:\\\/\\\/dkllaw.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dkllaw.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dkllaw.com\\\/wp-content\\\/uploads\\\/logo-sort.svg\",\"contentUrl\":\"https:\\\/\\\/dkllaw.com\\\/wp-content\\\/uploads\\\/logo-sort.svg\",\"width\":865,\"height\":119,\"caption\":\"Dianati &amp; Klink Larsen\"},\"image\":{\"@id\":\"https:\\\/\\\/dkllaw.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHRISTIAN VALEUR KIRKEGAARD - Dianati &amp; Klink Larsen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dkllaw.com\/en\/personer\/christian-valeur-kirkegaard\/","og_locale":"en_GB","og_type":"article","og_title":"CHRISTIAN VALEUR KIRKEGAARD - Dianati &amp; Klink Larsen","og_url":"https:\/\/dkllaw.com\/en\/personer\/christian-valeur-kirkegaard\/","og_site_name":"Dianati &amp; Klink Larsen","article_modified_time":"2026-09-01T08:04:29+00:00","og_image":[{"width":1638,"height":2048,"url":"https:\/\/dkllaw.com\/wp-content\/uploads\/Christan-Valeur-Kirkegaard-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dkllaw.com\/personer\/christian-valeur-kirkegaard\/","url":"https:\/\/dkllaw.com\/personer\/christian-valeur-kirkegaard\/","name":"CHRISTIAN VALEUR KIRKEGAARD - Dianati &amp; Klink Larsen","isPartOf":{"@id":"https:\/\/dkllaw.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dkllaw.com\/personer\/christian-valeur-kirkegaard\/#primaryimage"},"image":{"@id":"https:\/\/dkllaw.com\/personer\/christian-valeur-kirkegaard\/#primaryimage"},"thumbnailUrl":"https:\/\/dkllaw.com\/wp-content\/uploads\/Christan-Valeur-Kirkegaard-scaled.jpg","datePublished":"2025-06-05T10:46:04+00:00","dateModified":"2026-09-01T08:04:29+00:00","breadcrumb":{"@id":"https:\/\/dkllaw.com\/personer\/christian-valeur-kirkegaard\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dkllaw.com\/personer\/christian-valeur-kirkegaard\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dkllaw.com\/personer\/christian-valeur-kirkegaard\/#primaryimage","url":"https:\/\/dkllaw.com\/wp-content\/uploads\/Christan-Valeur-Kirkegaard-scaled.jpg","contentUrl":"https:\/\/dkllaw.com\/wp-content\/uploads\/Christan-Valeur-Kirkegaard-scaled.jpg","width":1638,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/dkllaw.com\/personer\/christian-valeur-kirkegaard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Forside","item":"https:\/\/dkllaw.com\/"},{"@type":"ListItem","position":2,"name":"Personer","item":"https:\/\/dkllaw.com\/personer\/"},{"@type":"ListItem","position":3,"name":"CHRISTIAN VALEUR KIRKEGAARD"}]},{"@type":"WebSite","@id":"https:\/\/dkllaw.com\/#website","url":"https:\/\/dkllaw.com\/","name":"Dianati &amp; Klink Larsen","description":"","publisher":{"@id":"https:\/\/dkllaw.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dkllaw.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/dkllaw.com\/#organization","name":"Dianati &amp; Klink Larsen","url":"https:\/\/dkllaw.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dkllaw.com\/#\/schema\/logo\/image\/","url":"https:\/\/dkllaw.com\/wp-content\/uploads\/logo-sort.svg","contentUrl":"https:\/\/dkllaw.com\/wp-content\/uploads\/logo-sort.svg","width":865,"height":119,"caption":"Dianati &amp; Klink Larsen"},"image":{"@id":"https:\/\/dkllaw.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dkllaw.com\/en\/wp-json\/wp\/v2\/person\/1691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dkllaw.com\/en\/wp-json\/wp\/v2\/person"}],"about":[{"href":"https:\/\/dkllaw.com\/en\/wp-json\/wp\/v2\/types\/person"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dkllaw.com\/en\/wp-json\/wp\/v2\/media\/3092"}],"wp:attachment":[{"href":"https:\/\/dkllaw.com\/en\/wp-json\/wp\/v2\/media?parent=1691"}],"wp:term":[{"taxonomy":"person-speciale","embeddable":true,"href":"https:\/\/dkllaw.com\/en\/wp-json\/wp\/v2\/person-speciale?post=1691"},{"taxonomy":"stilling","embeddable":true,"href":"https:\/\/dkllaw.com\/en\/wp-json\/wp\/v2\/stilling?post=1691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}